{"id":19802,"date":"2026-07-15T16:05:14","date_gmt":"2026-07-15T19:05:14","guid":{"rendered":"https:\/\/ligana104.com.br\/2021\/2026\/07\/15\/entregadora-morre-apos-bater-de-frente-e-ser-arremessada-durante-ultrapassagem-em-rondonopolis-assista\/"},"modified":"2026-07-15T16:05:15","modified_gmt":"2026-07-15T19:05:15","slug":"entregadora-morre-apos-bater-de-frente-e-ser-arremessada-durante-ultrapassagem-em-rondonopolis-assista","status":"publish","type":"post","link":"https:\/\/ligana104.com.br\/2021\/2026\/07\/15\/entregadora-morre-apos-bater-de-frente-e-ser-arremessada-durante-ultrapassagem-em-rondonopolis-assista\/","title":{"rendered":"Entregadora morre ap\u00f3s bater de frente e ser arremessada durante ultrapassagem em Rondon\u00f3polis; assista"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Uma entregadora por aplicativo identificada como Marisa Cardoso morreu ap\u00f3s um grave acidente de tr\u00e2nsito registrado nesta quarta-feira (15), na Rua Capit\u00e3o Ademir, no bairro Parque Universit\u00e1rio, em frente ao 4\u00ba Comando Regional da Pol\u00edcia Militar, em Rondon\u00f3polis. Uma c\u00e2mera de seguran\u00e7a registrou o exato momento da colis\u00e3o.<\/p>\n<p>As imagens mostram a motociclista tentando realizar uma ultrapassagem quando invade a pista contr\u00e1ria e colide de frente com uma picape que seguia no sentido oposto. Com a viol\u00eancia do impacto, ela passa por cima do ve\u00edculo e acaba arremessada v\u00e1rios metros \u00e0 frente.<\/p>\n<p>Equipes do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (Samu) prestaram atendimento ainda no local e encaminharam a v\u00edtima em estado grav\u00edssimo ao Hospital Regional.<\/p>\n<div class=\"g g-90\">\n<div class=\"g-single a-66\">\n<div style=\"position: relative; width: 100%;\">\n    <!-- Banner 3 --><\/p>\n<p>    <!-- Banner 4 --><\/p>\n<div id=\"banner4\" style=\"opacity: 0; transition: opacity 1s; width: 100%;\">\n        <a class=\"gofollow\" data-track=\"NjYsOTAsMSw2MA==\" href=\"https:\/\/www.instagram.com\/cdl.roo\" target=\"_blank\" rel=\"noopener\">&#13;<br \/>\n            &#13;<br \/>\n        <\/a>\n    <\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Apesar dos esfor\u00e7os da equipe m\u00e9dica, a entregadora n\u00e3o resistiu aos ferimentos. Ela sofreu m\u00faltiplas fraturas em decorr\u00eancia da forte colis\u00e3o e morreu pouco depois de dar entrada na unidade de sa\u00fade.<\/p>\n<p>O v\u00eddeo do acidente evidencia a viol\u00eancia do impacto. As circunst\u00e2ncias da trag\u00e9dia dever\u00e3o ser apuradas pelas autoridades competentes.<\/p>\n<p>V\u00eddeo mostra o exato momento do acidente:<\/p>\n<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/Da0vEyKC0wQ\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"\/>\n<p><!-- H&aacute; banners, eles s&atilde;o deficientes ou nenhum qualificado para este local! -->\t\t\t\t<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/rgtnews.com.br\/destaque\/entregadora-morre-apos-bater-de-frente-e-ser-arremessada-durante-ultrapassagem-em-rondonopolis-assista\/?utm_source=rss&#038;utm_medium=rss&#038;utm_campaign=entregadora-morre-apos-bater-de-frente-e-ser-arremessada-durante-ultrapassagem-em-rondonopolis-assista\">Fonte da Noticia <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma entregadora por aplicativo identificada como Marisa Cardoso morreu ap\u00f3s um grave acidente de tr\u00e2nsito registrado nesta quarta-feira (15), na Rua Capit\u00e3o Ademir, no bairro Parque Universit\u00e1rio, em frente ao 4\u00ba Comando Regional da Pol\u00edcia Militar, em Rondon\u00f3polis. Uma c\u00e2mera de seguran\u00e7a registrou o exato momento da colis\u00e3o. As imagens mostram a motociclista tentando realizar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19803,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/posts\/19802"}],"collection":[{"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/comments?post=19802"}],"version-history":[{"count":1,"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/posts\/19802\/revisions"}],"predecessor-version":[{"id":19804,"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/posts\/19802\/revisions\/19804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/media\/19803"}],"wp:attachment":[{"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/media?parent=19802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/categories?post=19802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/tags?post=19802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}