{"id":17541,"date":"2026-05-13T00:41:29","date_gmt":"2026-05-13T03:41:29","guid":{"rendered":"https:\/\/ligana104.com.br\/2021\/2026\/05\/13\/amiga-encontra-jovem-morta-com-sinais-de-violencia-e-caso-vira-um-misterio-em-mt-video\/"},"modified":"2026-05-13T00:41:30","modified_gmt":"2026-05-13T03:41:30","slug":"amiga-encontra-jovem-morta-com-sinais-de-violencia-e-caso-vira-um-misterio-em-mt-video","status":"publish","type":"post","link":"https:\/\/ligana104.com.br\/2021\/2026\/05\/13\/amiga-encontra-jovem-morta-com-sinais-de-violencia-e-caso-vira-um-misterio-em-mt-video\/","title":{"rendered":"Amiga encontra jovem morta com sinais de viol\u00eancia e caso vira um mist\u00e9rio em MT; v\u00eddeo"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Uma jovem de 23 anos identificada como  Clara Vit\u00f3ria da Silva, 23 anos, acabou encontrada morta com sinais de viol\u00eancia, no final da manh\u00e3 desta ter\u00e7a-feira (11), em Tangar\u00e1 da Serra-MT. <\/p>\n<p>De acordo com informa\u00e7\u00f5es, uma amiga da v\u00edtima foi quem a encontrou morta dentro de casa, no bairro Jardim Esmeralda, com sinais vis\u00edveis de viol\u00eancia. <\/p>\n<p>A Pol\u00edcia Civil recebeu o chamado e esteve no local. O Samu tamb\u00e9m atendeu a ocorr\u00eancia e confirmou a morte da jovem. <\/p>\n<p>As autoridades competentes investigam o caso.<\/p>\n<p>V\u00eddeo:<\/p>\n<blockquote class=\"instagram-media\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/DYPz4AqR3dk\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"\/>\n<p><!-- H&aacute; banners, eles s&atilde;o deficientes ou nenhum qualificado para este local! -->\t\t\t\t<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/rgtnews.com.br\/destaque\/amiga-encontra-jovem-morta-com-sinais-de-violencia-e-caso-vira-um-misterio-em-mt-video\/?utm_source=rss&#038;utm_medium=rss&#038;utm_campaign=amiga-encontra-jovem-morta-com-sinais-de-violencia-e-caso-vira-um-misterio-em-mt-video\">Fonte da Noticia <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma jovem de 23 anos identificada como Clara Vit\u00f3ria da Silva, 23 anos, acabou encontrada morta com sinais de viol\u00eancia, no final da manh\u00e3 desta ter\u00e7a-feira (11), em Tangar\u00e1 da Serra-MT. De acordo com informa\u00e7\u00f5es, uma amiga da v\u00edtima foi quem a encontrou morta dentro de casa, no bairro Jardim Esmeralda, com sinais vis\u00edveis de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17542,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/posts\/17541"}],"collection":[{"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/comments?post=17541"}],"version-history":[{"count":1,"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/posts\/17541\/revisions"}],"predecessor-version":[{"id":17543,"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/posts\/17541\/revisions\/17543"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/media\/17542"}],"wp:attachment":[{"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/media?parent=17541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/categories?post=17541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligana104.com.br\/2021\/wp-json\/wp\/v2\/tags?post=17541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}